{"id":13519,"date":"2015-03-19T14:50:10","date_gmt":"2015-03-19T17:50:10","guid":{"rendered":"https:\/\/www.mochileiros.com\/blog\/?p=13519"},"modified":"2018-12-19T12:40:30","modified_gmt":"2018-12-19T15:40:30","slug":"noivos-se-casam-38-vezes-ao-redor-do-mundo","status":"publish","type":"post","link":"https:\/\/www.mochileiros.com\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo","title":{"rendered":"Noivos se casam 38 vezes ao redor do mundo"},"content":{"rendered":"<p style=\"text-align: justify;\">Em fevereiro, a dupla Cheetah Platt e Rhiann Woodyard partiu com suas mochilas, de Los Angeles, na Calif\u00f3rnia (EUA) rumo a Bogot\u00e1, na Col\u00f4mbia para iniciar uma\u00a0jornada: casar-se em v\u00e1rios locais do mundo. O plano \u00e9 de se casarem 38 vezes durante 83 dias de viagem.<br \/>\n&#8220;Quando olh\u00e1vamos pre\u00e7os de um casamento tradicional na Calif\u00f3rnia (onde vivem), ach\u00e1vamos t\u00e3o caros e n\u00e3o senti nada especial&#8221;, contou a noiva Rhiann ao site <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.buzzfeed.com\/krystieyandoli\/this-couple-is-traveling-the-world-and-getting-married-on-6#.nm9gYXrXx\" target=\"_blank\" rel=\"noopener\">Buzzfeed<\/a><\/span>, frisando que muitas mulheres gastam muito dinheiro e tempo, al\u00e9m do estresse para um s\u00f3 dia de cerim\u00f4nia.<br \/>\nAinda de acordo com a publica\u00e7\u00e3o, eles conseguiram achar v\u00f4os de volta ao mundo por menos de USD 3000 por pessoa, conseguindo aterrizar em 11 pa\u00edses.<\/p>\n<div id=\"attachment_13520\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal01\" rel=\"attachment wp-att-13520\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13520\" class=\"size-full wp-image-13520\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01.jpg\" alt=\"Dupla rumo \u00e0 Col\u00f4mbia | Foto: Cheetah Platt e Rhiann Woodyard\/Arquivo pessoal\" width=\"1024\" height=\"563\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01-300x165.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01-768x422.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01-313x172.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal01-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13520\" class=\"wp-caption-text\">Dupla rumo \u00e0 Col\u00f4mbia |\u00a0Foto: Cheetah Platt e Rhiann Woodyard\/Arquivo pessoal<\/p><\/div>\n<p style=\"text-align: justify;\">Eles planejam se casar em todos os continentes, exceto na Ant\u00e1rtida, porque ali seria muito caro. Por enquanto eles j\u00e1 se casaram na Col\u00f4mbia, Espanha, Irlanda, Qu\u00eania, Egito, Marrocos, \u00cdndia e Tail\u00e2ndia. Em abril, quando voltarem para a casa, nos EUA, tamb\u00e9m oficializar\u00e3o a cerim\u00f4nia e pretendem fazer uma viagem de moto pelos pa\u00eds, tamb\u00e9m casando-se.<br \/>\nPlatt e Woodyard s\u00e3o acrobatas profissionais e muitas das fotos dos casamentos da dupla s\u00e3o fazendo performances. Ah, eles se vestem de branco em todas as cerim\u00f4nias.<br \/>\n&#8220;Dizem que voc\u00ea deve viajar com a pessoa com a qual vai se casar. N\u00f3s come\u00e7amos a aprender um com o outro a cada dia, mais e mais. Era exatamente o que eu queria: viajar pelo mundo com minha esposa e se casar com ela de novo e de novo e de tantas maneiras diferentes. Isso foi perfeito pra mim&#8221;, afirmou Platt.\u00a0Rom\u00e2ntico n\u00e9?<\/p>\n<p style=\"text-align: justify;\"><strong>Confira algumas imagens desse &#8216;Casamento around world&#8217;:<\/strong><\/p>\n<div id=\"attachment_13521\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal02\" rel=\"attachment wp-att-13521\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13521\" class=\"size-full wp-image-13521\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02.jpg\" alt=\"Em uma floresta colombiana | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal02-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13521\" class=\"wp-caption-text\">Em uma floresta colombiana |\u00a0Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13522\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal03\" rel=\"attachment wp-att-13522\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13522\" class=\"size-full wp-image-13522\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03.jpg\" alt=\"Em Madri, na Espanha | Foto: Cheetah Platt e Rhiann Woodyard\/Arquivo pessoal\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal03-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13522\" class=\"wp-caption-text\">Em Madri, na Espanha |\u00a0Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13523\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal05\" rel=\"attachment wp-att-13523\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13523\" class=\"size-full wp-image-13523\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05.jpg\" alt=\"Nas ru\u00ednas da Catedral Glendalough, na Irlanda | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal05-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13523\" class=\"wp-caption-text\">Nas ru\u00ednas da Catedral Glendalough, na Irlanda | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13524\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal06\" rel=\"attachment wp-att-13524\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13524\" class=\"size-full wp-image-13524\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06.jpg\" alt=\"Em outro ponto da Irlanda | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal06-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13524\" class=\"wp-caption-text\">Em outro ponto da Irlanda | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13526\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal07\" rel=\"attachment wp-att-13526\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13526\" class=\"size-full wp-image-13526\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07.jpg\" alt=\"E o n\u00famero de bandeiras na mochila vai aumentando... | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-1536x864.jpg 1536w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-2048x1152.jpg 2048w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-267x150.jpg 267w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-100x56.jpg 100w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-622x350.jpg 622w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-788x443.jpg 788w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal07-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13526\" class=\"wp-caption-text\">E o n\u00famero de bandeiras na mochila vai aumentando&#8230; | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13527\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal09\" rel=\"attachment wp-att-13527\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13527\" class=\"size-full wp-image-13527\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09.jpg\" alt=\"Em Nairobi, no Qu\u00eania | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal09-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13527\" class=\"wp-caption-text\">Em Nairobi, no Qu\u00eania | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13528\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal08\" rel=\"attachment wp-att-13528\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13528\" class=\"size-full wp-image-13528\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08.jpg\" alt=\"Casal no Egito | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal08-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13528\" class=\"wp-caption-text\">Casal no Egito | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13530\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal012\" rel=\"attachment wp-att-13530\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13530\" class=\"size-full wp-image-13530\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012.jpg\" alt=\"Na Tail\u00e2ndia | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal012-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13530\" class=\"wp-caption-text\">Na Tail\u00e2ndia | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13532\" style=\"width: 586px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal014\" rel=\"attachment wp-att-13532\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13532\" class=\"size-full wp-image-13532\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal014.jpg\" alt=\"Na \u00cdndia | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"576\" height=\"1024\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal014.jpg 576w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal014-169x300.jpg 169w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal014-313x556.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal014-11x20.jpg 11w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><p id=\"caption-attachment-13532\" class=\"wp-caption-text\">Na \u00cdndia | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<div id=\"attachment_13534\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mochileiros.com\/blog\/blog\/noivos-se-casam-38-vezes-ao-redor-do-mundo\/attachment\/casal00\" rel=\"attachment wp-att-13534\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13534\" class=\"size-full wp-image-13534\" src=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00.jpg\" alt=\"Nas Cascatas de Ouzoud, no Marrocos | Foto: Cheetah Platt e Rhiann Woodyard\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00.jpg 1024w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00-300x169.jpg 300w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00-768x432.jpg 768w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00-313x176.jpg 313w, https:\/\/www.mochileiros.com\/blog\/wp-content\/uploads\/2015\/03\/casal00-20x11.jpg 20w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-13534\" class=\"wp-caption-text\">Nas Cascatas de Ouzoud, no Marrocos | Foto: Cheetah Platt e Rhiann Woodyard<\/p><\/div>\n<p style=\"text-align: justify;\"><em>Nos perfis dos noivos no Facebook (<a href=\"https:\/\/www.facebook.com\/cheetah.platt\" target=\"_blank\" rel=\"noopener\">aqui<\/a> e <a href=\"https:\/\/www.facebook.com\/rhiannplatt\" target=\"_blank\" rel=\"noopener\">aqui<\/a>)\u00a0\u00e9 poss\u00edvel saber um pouco mais sobre essa hist\u00f3ria e conferir outras\u00a0bel\u00edssimas imagens.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em fevereiro, a dupla Cheetah Platt e Rhiann Woodyard partiu com suas mochilas, de Los Angeles, na Calif\u00f3rnia (EUA) rumo a Bogot\u00e1, na Col\u00f4mbia para iniciar uma\u00a0jornada: casar-se em v\u00e1rios locais do mundo. O plano \u00e9 de se casarem 38 vezes durante 83 dias de viagem. &#8220;Quando olh\u00e1vamos pre\u00e7os de um casamento tradicional na Calif\u00f3rnia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAoiELM5mIOjYRN0nfylq3_9r-8:productID":"","footnotes":""},"categories":[168],"tags":[],"class_list":["post-13519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/posts\/13519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/comments?post=13519"}],"version-history":[{"count":0,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/posts\/13519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/media\/13526"}],"wp:attachment":[{"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/media?parent=13519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/categories?post=13519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mochileiros.com\/blog\/wp-json\/wp\/v2\/tags?post=13519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}